{"id":25626,"date":"2024-11-28T18:39:35","date_gmt":"2024-11-28T17:39:35","guid":{"rendered":"https:\/\/dubairealestate.net\/projet-immobilier\/pelagos-par-igo\/"},"modified":"2026-07-02T11:55:48","modified_gmt":"2026-07-02T09:55:48","slug":"pelagos-par-igo","status":"publish","type":"immobilier","link":"https:\/\/dubairealestate.net\/en\/projets-sur-plan\/pelagos-par-igo\/","title":{"rendered":"Pelagos by IGO"},"content":{"rendered":"<p>Pelagos by IGO est un projet r\u00e9sidentiel unique situ\u00e9 dans le prestigieux quartier de Dubai Marina, offrant un style de vie luxueux avec une gamme d\u2019appartements pour satisfaire des go\u00fbts vari\u00e9s. Les acheteurs potentiels peuvent choisir parmi des studios \u00e9l\u00e9gants, des appartements spacieux d\u2019une chambre et des options de deux chambres aux vues \u00e9poustouflantes. Chaque appartement est minutieusement con\u00e7u pour offrir des panoramas ininterrompus sur la Dubai Marina ou sur la mer scintillante, permettant aux r\u00e9sidents de profiter de vues magnifiques et d\u2019un mode de vie vibrant et embl\u00e9matique. Pelagos by IGO incarne un parfait \u00e9quilibre entre glamour, identit\u00e9 et libert\u00e9, red\u00e9finissant la vie contemporaine.<\/p>\n<p>Des commodit\u00e9s de classe mondiale pour un style de vie dynamique<\/p>\n<p>Les commodit\u00e9s de classe mondiale de Pelagos by IGO am\u00e9liorent l\u2019exp\u00e9rience de vie des r\u00e9sidents, leur garantissant un mode de vie dynamique. Pour les passionn\u00e9s de fitness, une salle de sport enti\u00e8rement \u00e9quip\u00e9e offre des \u00e9quipements de pointe dans un environnement moderne et \u00e9l\u00e9gant. Les r\u00e9sidents peuvent \u00e9galement se d\u00e9tendre au bord de la piscine immacul\u00e9e ou organiser des rassemblements dans la salle polyvalente. Pour ceux qui appr\u00e9cient les activit\u00e9s en plein air, l\u2019espace de d\u00e9tente ext\u00e9rieur est parfait pour la relaxation ou les rencontres conviviales. Ces commodit\u00e9s combinent fonctionnalit\u00e9 et luxe, faisant de chaque journ\u00e9e une v\u00e9ritable escapade.<\/p>\n<p>Un emplacement de choix au bord de l\u2019eau et un design \u00e9poustouflant<\/p>\n<p>Au-del\u00e0 de ses int\u00e9rieurs somptueux et de ses commodit\u00e9s luxueuses, Pelagos by IGO se distingue par son emplacement in\u00e9gal\u00e9 et son design spectaculaire, garantissant aux r\u00e9sidents d\u2019\u00eatre toujours entour\u00e9s de beaut\u00e9 et d\u2019\u00e9nergie. Ce d\u00e9veloppement est parfait pour ceux qui recherchent un mode de vie actif et dynamique, tout en profitant du confort de la vie moderne. Son emplacement au bord de l\u2019eau offre bien plus que de simples vues, procurant une sensation de s\u00e9r\u00e9nit\u00e9 au c\u0153ur de l\u2019effervescence urbaine. La combinaison d\u2019appartements luxueux, de panoramas saisissants et de commodit\u00e9s haut de gamme fait de Pelagos by IGO bien plus qu\u2019une simple r\u00e9sidence\u2014c\u2019est une v\u00e9ritable d\u00e9claration de style de vie.<\/p>","protected":false},"author":8,"featured_media":11201,"parent":0,"template":"","format":"standard","meta":{"vendu":"Disponible","plan-de-paiement-":"Avec plan","prix-projet":"1221000","type-de-propriete":{"Studio":"true","Appartement":"true","Penthouse":"false","Townhouse":"false","Villa":"false"},"chambre":{"Studio":"true","1":"true","2":"true","3":"true","4":"false","5+":"false"},"salles-de-bains":{"1":"false","2":"true","3":"true","4":"true","5+":"false"},"amenities":{"Piscine":"true","Salle de sport":"true","Aire de jeux":"true","Parking":"true","Se\u0301curite\u0301 24\/7":"true","Lagons":"false","Jardins paysagers":"true","Pistes de jogging":"false","Points de ventes":"false","Mall":"false","\u00c9cole":"false","Piste cyclable":"false","Terrain de sport":"false","Conciergerie":"false","Voiturier":"false","Cine\u0301ma":"false","Sauna \/ spa":"false","Golf":"false","Plage prive\u0301e":"false"},"surfacesqft":"","surfacesqft_max":"","texte-surface":"","prix_studio":"","prix_1_chambre":"","prix_2_chambres":"","prix_3_chambres":"","prix_4_chambres":"","prix_5_chambres":"","ville--emirats":"Dubai","_address":"Pelagos by IGO","reservation":"20","construction":"30","remise-des-cles":"50","post-handover-":"Sans post handover","apres-remise-des-cles":"","gallerie_image":["11201","11194"],"video-":"Sans video","lien-de-la-video":"","footnotes":""},"immo-en-avant":[],"categorie-immobilier":[812],"promoteurs":[436],"quartiers":[336],"class_list":["post-25626","immobilier","type-immobilier","status-publish","format-standard","has-post-thumbnail","hentry","categorie-immobilier-projets-sur-plan","promoteurs-igo","quartiers-dubai-marina"],"_links":{"self":[{"href":"https:\/\/dubairealestate.net\/en\/wp-json\/wp\/v2\/immobilier\/25626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dubairealestate.net\/en\/wp-json\/wp\/v2\/immobilier"}],"about":[{"href":"https:\/\/dubairealestate.net\/en\/wp-json\/wp\/v2\/types\/immobilier"}],"author":[{"embeddable":true,"href":"https:\/\/dubairealestate.net\/en\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":1,"href":"https:\/\/dubairealestate.net\/en\/wp-json\/wp\/v2\/immobilier\/25626\/revisions"}],"predecessor-version":[{"id":28408,"href":"https:\/\/dubairealestate.net\/en\/wp-json\/wp\/v2\/immobilier\/25626\/revisions\/28408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dubairealestate.net\/en\/wp-json\/wp\/v2\/media\/11201"}],"wp:attachment":[{"href":"https:\/\/dubairealestate.net\/en\/wp-json\/wp\/v2\/media?parent=25626"}],"wp:term":[{"taxonomy":"immo-en-avant","embeddable":true,"href":"https:\/\/dubairealestate.net\/en\/wp-json\/wp\/v2\/immo-en-avant?post=25626"},{"taxonomy":"categorie-immobilier","embeddable":true,"href":"https:\/\/dubairealestate.net\/en\/wp-json\/wp\/v2\/categorie-immobilier?post=25626"},{"taxonomy":"promoteurs","embeddable":true,"href":"https:\/\/dubairealestate.net\/en\/wp-json\/wp\/v2\/promoteurs?post=25626"},{"taxonomy":"quartiers","embeddable":true,"href":"https:\/\/dubairealestate.net\/en\/wp-json\/wp\/v2\/quartiers?post=25626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}